{"id":81276,"date":"2026-05-14T14:34:58","date_gmt":"2026-05-14T12:34:58","guid":{"rendered":"https:\/\/cmstores.com\/recambio\/juego-de-alfombras-triumph-spitfire-hoja-de-otono\/"},"modified":"2026-07-20T15:52:15","modified_gmt":"2026-07-20T13:52:15","slug":"triumph-spitfire-carpet-set-autumn-leaf","status":"publish","type":"product","link":"https:\/\/cmstores.com\/en\/triumph-spitfire-carpet-set-autumn-leaf\/","title":{"rendered":"Triumph Spitfire carpet set Autumn Leaf"},"content":{"rendered":"<p>Triumph Spitfire carpet set Autumn Leaf<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Triumph Spitfire carpet set Autumn Leaf<\/p>\n","protected":false},"featured_media":53695,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[3081],"product_tag":[],"product_model":[],"class_list":["post-81276","product","type-product","status-publish","has-post-thumbnail","product_cat-interior-14-en","first","instock","taxable","shipping-taxable","purchasable","product-type-simple"],"_links":{"self":[{"href":"https:\/\/cmstores.com\/en\/wp-json\/wp\/v2\/product\/81276","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cmstores.com\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/cmstores.com\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/cmstores.com\/en\/wp-json\/wp\/v2\/comments?post=81276"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cmstores.com\/en\/wp-json\/wp\/v2\/media\/53695"}],"wp:attachment":[{"href":"https:\/\/cmstores.com\/en\/wp-json\/wp\/v2\/media?parent=81276"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/cmstores.com\/en\/wp-json\/wp\/v2\/product_brand?post=81276"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/cmstores.com\/en\/wp-json\/wp\/v2\/product_cat?post=81276"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/cmstores.com\/en\/wp-json\/wp\/v2\/product_tag?post=81276"},{"taxonomy":"product_model","embeddable":true,"href":"https:\/\/cmstores.com\/en\/wp-json\/wp\/v2\/product_model?post=81276"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}