{"id":21409,"date":"2026-05-28T10:57:05","date_gmt":"2026-05-28T08:57:05","guid":{"rendered":"https:\/\/cmstores.com\/?post_type=product&#038;p=21409"},"modified":"2026-05-28T10:57:05","modified_gmt":"2026-05-28T08:57:05","slug":"jaguar-daimler-old-models","status":"publish","type":"product","link":"https:\/\/cmstores.com\/en\/jaguar-daimler-old-models\/","title":{"rendered":"Jaguar Daimler (Old Models) Parts Catalogue &amp; Workshop Manual CD-ROM"},"content":{"rendered":"<p>CD-ROM with parts catalogue and workshop manual for Jaguar Daimler (Old Models).<\/p>\n","protected":false},"excerpt":{"rendered":"<p>CD-ROM with parts catalogue and workshop manual for Jaguar Daimler (Old Models).<\/p>\n","protected":false},"featured_media":69747,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[1213],"product_tag":[],"product_model":[],"class_list":["post-21409","product","type-product","status-publish","has-post-thumbnail","product_cat-jaguar-cds-dvds","first","instock","taxable","shipping-taxable","purchasable","product-type-simple"],"_links":{"self":[{"href":"https:\/\/cmstores.com\/en\/wp-json\/wp\/v2\/product\/21409","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cmstores.com\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/cmstores.com\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/cmstores.com\/en\/wp-json\/wp\/v2\/comments?post=21409"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cmstores.com\/en\/wp-json\/wp\/v2\/media\/69747"}],"wp:attachment":[{"href":"https:\/\/cmstores.com\/en\/wp-json\/wp\/v2\/media?parent=21409"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/cmstores.com\/en\/wp-json\/wp\/v2\/product_brand?post=21409"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/cmstores.com\/en\/wp-json\/wp\/v2\/product_cat?post=21409"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/cmstores.com\/en\/wp-json\/wp\/v2\/product_tag?post=21409"},{"taxonomy":"product_model","embeddable":true,"href":"https:\/\/cmstores.com\/en\/wp-json\/wp\/v2\/product_model?post=21409"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}